{"id":27481,"date":"2024-10-09T14:49:00","date_gmt":"2024-10-09T18:49:00","guid":{"rendered":"https:\/\/flex-lock.com\/sable-fin-de-jointoiement-gator-nitro-x\/"},"modified":"2026-06-19T16:46:59","modified_gmt":"2026-06-19T20:46:59","slug":"sable-fin-de-jointoiement-gator-nitro-x","status":"publish","type":"page","link":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/","title":{"rendered":"Sable fin de jointoiement Gator Nitro-X"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27481\" class=\"elementor elementor-27481 elementor-27319\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa3976f e-flex e-con-boxed e-con e-parent\" data-id=\"aa3976f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e50c2ff e-con-full e-flex e-con e-child\" data-id=\"e50c2ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44273e1 elementor-widget elementor-widget-image\" data-id=\"44273e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"206\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp\" class=\"attachment-full size-full wp-image-27914\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp 640w, https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1-300x97.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a628700 e-con-full e-flex e-con e-child\" data-id=\"a628700\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-544b4d6 elementor-widget elementor-widget-menu-anchor\" data-id=\"544b4d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"videos\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e2c3f5 elementor-widget elementor-widget-html\" data-id=\"5e2c3f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/x6VaBgKB_Jk?si=5qubH83VJs4x_i_E\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6944e79e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6944e79e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c54e4dc\" data-id=\"2c54e4dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24ef242f elementor-nav-menu__align-justify elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"24ef242f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-24ef242f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27547\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\">Description<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27548\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\">Id\u00e9al pour<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27549\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\">Caract\u00e9ristiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27550\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\">Emballage<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27551\"><a href=\"#installation\" class=\"elementor-item elementor-item-anchor\">Installation<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27552\"><a target=\"_blank\" href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/documentation\/2026\/jointing-material\/ft\/61-ft-flexlock-gatornitrox-sand.pdf\" class=\"elementor-item\">FT<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-24ef242f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27547\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Description<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27548\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Id\u00e9al pour<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27549\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Caract\u00e9ristiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27550\"><a href=\"#avantages\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Emballage<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27551\"><a href=\"#installation\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Installation<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-27552\"><a target=\"_blank\" href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/documentation\/2026\/jointing-material\/ft\/61-ft-flexlock-gatornitrox-sand.pdf\" class=\"elementor-item\" tabindex=\"-1\">FT<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13471f9b elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"13471f9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aa49069\" data-id=\"3aa49069\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c4dd5e9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c4dd5e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60afacc2\" data-id=\"60afacc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38c5db7e elementor-widget elementor-widget-image\" data-id=\"38c5db7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"311\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/11\/20240533-Alliance-GatorNitroSand-X-8L_Plastic_13sept24-FLAT-2-fr.webp\" class=\"attachment-full size-full wp-image-27966\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/11\/20240533-Alliance-GatorNitroSand-X-8L_Plastic_13sept24-FLAT-2-fr.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/11\/20240533-Alliance-GatorNitroSand-X-8L_Plastic_13sept24-FLAT-2-fr-289x300.webp 289w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a689cf\" data-id=\"3a689cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-201f4308 elementor-widget elementor-widget-heading\" data-id=\"201f4308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sable fin de jointoiement<br>Gator Nitro-X<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78cfaebf elementor-widget elementor-widget-spacer\" data-id=\"78cfaebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b77e291 elementor-widget elementor-widget-image\" data-id=\"b77e291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"65\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Rapid-Flow-Technology-logo-FR.webp\" class=\"attachment-large size-large wp-image-27738\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Rapid-Flow-Technology-logo-FR.webp 1000w, https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Rapid-Flow-Technology-logo-FR-300x24.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Rapid-Flow-Technology-logo-FR-768x62.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3706b601 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3706b601\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5381e179\" data-id=\"5381e179\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eef30dc elementor-widget elementor-widget-menu-anchor\" data-id=\"3eef30dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"avantages\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c54ce69 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c54ce69\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-695280f8\" data-id=\"695280f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41ae3602 advantages-tab-menu elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"41ae3602\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1101\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1101\" aria-expanded=\"false\">Description<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1102\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1102\" aria-expanded=\"false\">Id\u00e9al pour<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1103\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1103\" aria-expanded=\"false\">Caract\u00e9ristiques<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1104\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1104\" aria-expanded=\"false\">Couleurs<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1105\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1105\" aria-expanded=\"false\">Entretien<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1106\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1106\" aria-expanded=\"false\">Superficie couverte<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1107\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1107\" aria-expanded=\"false\">Entreposage<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1108\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1108\" aria-expanded=\"false\">Emballage<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1101\" aria-expanded=\"false\">Description<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1101\" tabindex=\"0\" hidden=\"false\"><p><span class=\"bold-text-alliance\">LE SABLE DE JOINTOIEMENT FIN GATOR NITRO-X<\/span> est le mat\u00e9riau de jointoiement \u00e0 faible perm\u00e9abilit\u00e9 et durcissant lorsque expos\u00e9 \u00e0 l\u2019air. C\u2019est un m\u00e9lange pr\u00eat \u00e0 l\u2019emploi de sable fin calibr\u00e9 et d\u2019une nouvelle formule de r\u00e9sine exclusive qui durcit au contact de l\u2019air, se solidifiant de haut en bas du joint. Le produit peut \u00eatre install\u00e9 par temps sec ou humide. La technologie \u00e0 d\u00e9bit rapide permet une installation simple et rapide.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1102\" aria-expanded=\"false\">Id\u00e9al pour<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1102\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1102\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Base drainante traditionnelle<\/li><li>Base perm\u00e9able<\/li><li>Base hybride<\/li><li>Gator Base (usage pi\u00e9tonnier uniquement)<\/li><li>Pav\u00e9s en b\u00e9ton, dalles en b\u00e9ton, pierres naturelles ou pierres reconstitu\u00e9es<\/li><li>Tuiles de porcelaine, pav\u00e9s de porcelaine ou dalles de porcelaine pour ext\u00e9rieur<\/li><li>Stationnements r\u00e9sidentielles pour v\u00e9hicules l\u00e9gers<\/li><li>Patios, piscines, trottoirs et sentiers<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1103\" aria-expanded=\"false\">Caract\u00e9ristiques<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1103\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1103\" tabindex=\"0\" hidden=\"hidden\"><div class=\"centering\"><img decoding=\"async\" class=\"alignright wp-image-2857 size-medium no-float\" style=\"width: 100%; max-width: 600px;\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Xtra-nitro-x-FR.webp\" data-wp-editing=\"1\" \/><\/div><div class=\"centering\"><div class=\"text-break\">\u00a0<\/div><\/div><ul><li>Largeur de joint de 1\/8\u201d (3 mm) \u00e0 1\/4\u201d (6 mm) pour les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur<\/li><li>Largeur de joint de 1\/8\u201d (3 mm) \u00e0 2\u201d (50 mm) pour les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es<\/li><li>Profondeur du joint minimum 3\/4\u201d (20 mm) \u00e0 un maximum de 2-3\/8\u201d (60 mm)<\/li><li>TECHNOLOGIE \u00c0 D\u00c9BIT RAPIDE<\/li><li>Installation simple et rapide<\/li><li>XTRA fine granulom\u00e9trie du sable de jointoiement<\/li><li>Xtra Faible perm\u00e9abilit\u00e9<\/li><li>XTRA r\u00e9sistance de haut en bas<\/li><li>Appliquer par temps de pluie ou sec<\/li><li>Fonctionne \u00e0 partir de 3\u00b0C<\/li><\/ul><p>*Les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur\u00a0<span class=\"bold-text-alliance\">ne doivent pas pr\u00e9senter de mouvement avant ou apr\u00e8s l\u2019installation\u00a0<\/span>de\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0dans les joints. Si les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur bougent ou basculent, cela r\u00e9sulte d\u2019une pr\u00e9paration inad\u00e9quate de la sous-fondation. Pour plus de clart\u00e9,\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0n\u2019emp\u00eachera pas les forces lat\u00e9rales ou de rotations qui sont g\u00e9n\u00e9r\u00e9es sur les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et sur les installations de tuiles de porcelaine, de pav\u00e9s de porcelaine ou de dalles de porcelaine pour ext\u00e9rieur.\u00a0<span class=\"bold-text-alliance\">Tout mouvement d\u2019un mat\u00e9riau de pavage annule la garantie<\/span>.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1104\" aria-expanded=\"false\">Couleurs<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1104\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1104\" tabindex=\"0\" hidden=\"hidden\"><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29755\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-scaled.png\" alt=\"\" width=\"800\" height=\"52\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-scaled.png 2560w, https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-300x19.png 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-1024x66.png 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-768x50.png 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-1536x99.png 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2026\/06\/20260406-Nitro-X-5-Color-Web-FRA-2048x133.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1105\" aria-expanded=\"false\">Entretien<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1105\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1105\" tabindex=\"0\" hidden=\"hidden\"><p><span class=\"bold-text-alliance\">ENTRETIEN DE LA SURFACE PAV\u00c9E<\/span><\/p><p>Lors de l\u2019entretien de la surface pav\u00e9e, appliquez le shampooing Gator pour nettoyer toute la surface, y compris les joints de pierre. Lavez, rincez et enlevez tout r\u00e9sidu en utilisant un tuyau et un pistolet d\u2019arrosage r\u00e9gl\u00e9 \u00e0 \u00ab\u00a0douche\u00a0\u00bb (shower) avec la pression d\u2019eau maximale normale de tout b\u00e2timent r\u00e9sidentiel ou commercial, typiquement 550 kPa (80 psi).<\/p><p><span class=\"bold-text-alliance\">MOUSSE<\/span><\/p><p>Le <span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> ne causera ni n\u2019emp\u00eachera la mousse, la moisissure et le mildiou. La mousse et la moisissure sont la r\u00e9sultante de certaines conditions, notamment l\u2019humidit\u00e9 excessive, l\u2019ombre, l\u2019absence de ventilation, un nettoyage ou un entretien inad\u00e9quat et des r\u00e9sidus de terre ou d\u2019autres d\u00e9bris organiques sur le produit.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1106\" aria-expanded=\"false\">Superficie couverte<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1106\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1106\" tabindex=\"0\" hidden=\"hidden\"><p><span class=\"bold-text-alliance\">La quantit\u00e9 requise d\u00e9pend de la taille des joints. La quantit\u00e9 requise d\u00e9pend de la taille du produit et de ses joints. Un seau de 27,5 lb (12,5 kg). PAV\u00c9 OU PIERRE 12&Prime; x 12&Prime; x 2-3\/8&Prime; (30 cm X 30 cm X 6 cm) \u2022 Tuile de porcelaine 24&Prime; x 24&Prime; x 3\/4&Prime; (60 cm x 60 cm x 20 mm).<\/span><\/p><table id=\"coverage-table\" cellpadding=\"10\"><tbody><tr><th>Tuile de porcelaine 60 cm x 60 cm x 20 mm (24&Prime; x 24&Prime; x 3\/4&Prime;) avec joints de 3 mm (1\/8\u2033) de largeur \u2022 Pav\u00e9 ou pierre 30 cm x 30 cm x 60 mm (12\u201d x 12\u201d x 2-3\/8\u201d) avec joints de 5 mm (3\/16\u2033) \u00e0 25 mm (1\u2033)<\/th><th>Taupe<\/th><th>Platine<\/th><th>Gris canon<\/th><th>Noir<\/th><th>Vanille<\/th><\/tr><tr><td>Joint 1\/8&Prime; (Tuile de porcelaine)<\/td><td>374 pi. ca.<\/td><td>348 pi. ca.<\/td><td>348 pi. ca.<\/td><td>323 pi. ca.<\/td><td>374 pi. ca.<\/td><\/tr><tr><td>Joint 3 mm (Tuile de porcelaine)<\/td><td>35 m. ca.<\/td><td>33 m. ca.<\/td><td>33 m. ca.<\/td><td>31 m. ca.<\/td><td>35 m. ca.<\/td><\/tr><tr><td>Joint 1\/8&Prime; (Pav\u00e9s en b\u00e9ton)<\/td><td>64 pi. ca.<\/td><td>59 pi. ca.<\/td><td>59 pi. ca.<\/td><td>54 pi. ca.<\/td><td>64 pi. ca.<\/td><\/tr><tr><td>Joint 3 mm (Pav\u00e9s en b\u00e9ton)<\/td><td>6 m. ca.<\/td><td>5.5 m. ca.<\/td><td>5.5 m. ca.<\/td><td>5.1 m. ca.<\/td><td>6 m. ca.<\/td><\/tr><tr><td>Joint 3\/16&Prime; (Pav\u00e9s en b\u00e9ton)<\/td><td>38 pi. ca.<\/td><td>35 pi. ca.<\/td><td>35 pi. ca.<\/td><td>33 pi. ca.<\/td><td>38 pi. ca.<\/td><\/tr><tr><td>Joint 5 mm (Pav\u00e9s en b\u00e9ton)<\/td><td>3.6 m. ca.<\/td><td>3.3 m. ca.<\/td><td>3.3 m. ca.<\/td><td>3.1 m. ca.<\/td><td>3.6 m. ca.<\/td><\/tr><tr><td>Joint 3\/4&Prime; (Pav\u00e9s en b\u00e9ton)<\/td><td>10.4 pi. ca.<\/td><td>9.6 pi. ca.<\/td><td>9.6 pi. ca.<\/td><td>9 pi. ca.<\/td><td>10.4 pi. ca.<\/td><\/tr><tr><td>Joint 19 mm (Pav\u00e9s en b\u00e9ton)<\/td><td>0.97 m. ca.<\/td><td>0.9 m. ca.<\/td><td>0.9 m. ca.<\/td><td>0.84 m. ca.<\/td><td>0.97 m. ca.<\/td><\/tr><tr><td>Joint 1&Prime; (Pav\u00e9s en b\u00e9ton)<\/td><td>8 pi. ca.<\/td><td>7 pi. ca.<\/td><td>7 pi. ca.<\/td><td>6.8 pi. ca.<\/td><td>8 pi. ca.<\/td><\/tr><tr><td>Joint 25 mm (Pav\u00e9s en b\u00e9ton)<\/td><td>0.75 m. ca.<\/td><td>0.69 m. ca.<\/td><td>0.69 m. ca.<\/td><td>0.65 m. ca.<\/td><td>0.75 m. ca.<\/td><\/tr><\/tbody><\/table><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2069 \" src=\"\/wp-content\/uploads\/2021\/06\/sand-calculator.png\" alt=\"\" width=\"16\" height=\"23\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2021\/06\/sand-calculator.png 348w, https:\/\/flex-lock.com\/wp-content\/uploads\/2021\/06\/sand-calculator-214x300.png 214w\" sizes=\"(max-width: 16px) 100vw, 16px\" \/> <a href=\"\/fr\/calculateur-simplifie-pour-sable-polymerique-et-sable-nitro\"><span class=\"bold-text-alliance\">CALCULATRICE DE SABLE<\/span><\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1107\" aria-expanded=\"false\">Entreposage<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1107\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1107\" tabindex=\"0\" hidden=\"hidden\"><p>24 mois en zone froide. Stocker \u00e0 l\u2019ext\u00e9rieur sous un abri, \u00e0 l\u2019abri du soleil, ou \u00e0 l\u2019int\u00e9rieur \u00e0 des temp\u00e9ratures allant de -30 \u00e0 30 \u00b0C. La palette de <span class=\"bold-text-alliance\">GATOR NITRO-X<\/span> peut \u00eatre empil\u00e9e doublement pour le stockage, mais pas lors du transport.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1108\" aria-expanded=\"false\">Emballage<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1108\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1108\" tabindex=\"0\" hidden=\"hidden\"><table id=\"coverage-table\" cellpadding=\"10\">\n<tbody>\n<tr>\n<th>Produit<\/th>\n<th>Format au d\u00e9tail<\/th>\n<th>Unit\u00e9s par palette<\/th>\n<\/tr>\n<tr>\n<td><span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> &#8211; Black<\/td>\n<td>27.5 lb (12.5 kg)<\/td>\n<td>48<\/td>\n<\/tr>\n<tr>\n<td><span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> &#8211; Gris canon<\/td>\n<td>27.5 lb (12.5 kg)<\/td>\n<td>48<\/td>\n<\/tr>\n<tr>\n<td><span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> &#8211; Taupe<\/td>\n<td>27.5 lb (12.5 kg)<\/td>\n<td>48<\/td>\n<\/tr>\n<tr>\n<td><span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> &#8211; Platinum<\/td>\n<td>27.5 lb (12.5 kg)<\/td>\n<td>48<\/td>\n<\/tr>\n<tr>\n<td><span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span> &#8211; Vanille<\/td>\n<td>27.5 lb (12.5 kg)<\/td>\n<td>48<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-304288cb elementor-widget elementor-widget-html\" data-id=\"304288cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\njQuery('#menu-1-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27547 > a').click(function() { jQuery('#elementor-tab-title-1101').click(); });\r\njQuery('#menu-2-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27547 > a').click(function() { jQuery('#elementor-tab-title-1101').click(); });\r\njQuery('#menu-1-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27548 > a').click(function() { jQuery('#elementor-tab-title-1102').click(); });\r\njQuery('#menu-2-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27548 > a').click(function() { jQuery('#elementor-tab-title-1102').click(); });\r\njQuery('#menu-1-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27549 > a').click(function() { jQuery('#elementor-tab-title-1103').click(); });\r\njQuery('#menu-2-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27549 > a').click(function() { jQuery('#elementor-tab-title-1103').click(); });\r\njQuery('#menu-1-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27550 > a').click(function() { jQuery('#elementor-tab-title-1108').click(); });\r\njQuery('#menu-2-24ef242f > li.menu-item.menu-item-type-custom.menu-item-object-custom.menu-item-27550 > a').click(function() { jQuery('#elementor-tab-title-1108').click(); });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65c39121 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65c39121\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-659111fb\" data-id=\"659111fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1069193e elementor-widget elementor-widget-menu-anchor\" data-id=\"1069193e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"installation\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bfb9b8 elementor-widget elementor-widget-heading\" data-id=\"28bfb9b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOTES IMPORTANTES POUR L\u2019INSTALLATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c8be837 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c8be837\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6fca7f\" data-id=\"a6fca7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-785f6580 elementor-widget elementor-widget-text-editor\" data-id=\"785f6580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol type=\"A\"><li>Consulter toujours la derni\u00e8re\u00a0<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/documentation\/tds\/fr\/alliance-gator-ft-june-16-2025-gator-nitro-x.pdf\" target=\"_blank\" rel=\"noopener\">Fiche technique (FT)<\/a>\u00a0de\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0sur AllianceGator.com\/canada\/fr avant l\u2019installation<\/li><li>Les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur\u00a0<span class=\"bold-text-alliance\">ne doivent pas pr\u00e9senter de mouvement avant ou apr\u00e8s l\u2019installation<\/span>\u00a0de\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0dans les joints. Si les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur bougent ou basculent, cela r\u00e9sulte d\u2019une pr\u00e9paration inad\u00e9quate de la sous-fondation. Pour plus de clart\u00e9,\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0n\u2019emp\u00eachera pas les forces lat\u00e9rales ou de rotation qui sont g\u00e9n\u00e9r\u00e9es sur les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et sur les installations de tuiles de porcelaine, de pav\u00e9s de porcelaine ou de dalles de porcelaine pour ext\u00e9rieur.\u00a0<span class=\"bold-text-alliance\">Tout mouvement d\u2019un mat\u00e9riau de pavage annule la garantie<\/span>.<\/li><li><span class=\"bold-text-alliance\">GATOR NITRO-X\u00a0<\/span>peut \u00eatre install\u00e9 par temps de pluie ou sec. La surface de pavage doit \u00eatre pr\u00e9-mouill\u00e9e avant la pose et doit rester mouill\u00e9e tout au long du processus de pose, faute de quoi des taches peuvent appara\u00eetre.<\/li><li><span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0doit \u00eatre install\u00e9 \u00e0 une temp\u00e9rature sup\u00e9rieure \u00e0 3 \u00b0C.<\/li><li>Largeur de joint de 1\/8\u201d (3 mm) \u00e0 1\/4\u201d (6 mm) pour les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur.<br \/>Largeur de joint de 1\/8\u2019\u2019 (3 mm) \u00e0 2\u201d (50 mm) pour les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es.<\/li><li>Profondeur du joint : Minimum 3\/4\u201d (20 mm) Maximum 2 3\/8\u201d (60 mm).<\/li><li>Temps de travail : Le produit doit \u00eatre appliqu\u00e9 dans un d\u00e9lai d\u2019environ 45 minutes.<\/li><li><span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0ne peut \u00eatre utilis\u00e9 que sur une application de base drainante.<\/li><li>La surface pav\u00e9e peut \u00eatre utilis\u00e9e apr\u00e8s 18 heures.<\/li><li>\u00c9viter le lavage sous pression pendant au moins 28 jours apr\u00e8s l\u2019application.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23b6c1fa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23b6c1fa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54580374\" data-id=\"54580374\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54617abf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54617abf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-43ff333c\" data-id=\"43ff333c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ce5106b elementor-widget elementor-widget-heading\" data-id=\"6ce5106b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">PR\u00c9PARATION REQUISE DE LA SOUS-FONDATION<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dcaec03 elementor-widget elementor-widget-text-editor\" data-id=\"5dcaec03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le\u00a0<span class=\"bold-text-alliance\">SABLE FIN DE JOINTOIEMENT GATOR NITRO-X<\/span>\u00a0est recommand\u00e9 pour une vari\u00e9t\u00e9 d\u2019utilisations, y compris les patios, les all\u00e9es, les pourtours de piscine et les applications v\u00e9hiculaires r\u00e9sidentielles. Les pav\u00e9s, pierres reconstitu\u00e9es ou naturelles doivent \u00eatre install\u00e9s sur l\u2019un des 5 syst\u00e8mes de base optionnels illustr\u00e9s ci-dessous: Nous d\u00e9montrons 5 diff\u00e9rentes applications de 1-4B<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e0c9a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e0c9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae19858\" data-id=\"ae19858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27a8fe4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27a8fe4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52abd21\" data-id=\"52abd21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3acd3fb elementor-widget elementor-widget-heading\" data-id=\"3acd3fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">Option 1 Base drainante traditionnelle<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c0767 elementor-widget elementor-widget-text-editor\" data-id=\"44c0767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une g\u00e9otextile\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-geogrille-geotextile\/gator-fabric-gf4-4\/\">Gator Fabric GF4.4<\/a>\u00a0couvrant le fond et les c\u00f4t\u00e9s de la zone excav\u00e9e.<\/li><li>Fondation en pierre concass\u00e9es et compact\u00e9e 0-3\/4\u2019\u2019 (0-20 mm), de 4-6\u201d (10-15 cm) d\u2019\u00e9paisseur.<\/li><li>Lit de pose de 1\u201d (25 mm) de sable ou de pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloqueront*) (<a href=\"https:\/\/www.youtube.com\/embed\/MkH1_MIB750\" target=\"_blank\" rel=\"noopener\">ASTM N\u00b0 9<\/a>).<\/li><li>Fixer la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-edge-flex-rigide\/\">Gator Edge<\/a>\u00a0sur la pierre concass\u00e9e compact\u00e9e et s\u2019assurer que la section verticale de la bordure \u00e9pouse les pav\u00e9s, de sorte qu\u2019aucun mat\u00e9riau de pose ne migre vers l\u2019ext\u00e9rieur. Voir le diagramme 1.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-01a9781\" data-id=\"01a9781\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8436019 elementor-widget elementor-widget-image\" data-id=\"8436019\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gator-nitro-x-jan-13-2025cdn-fr-diagram-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxODksInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvZ2F0b3Itbml0cm8teC1qYW4tMTMtMjAyNWNkbi1mci1kaWFncmFtLTEud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"462\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1-1024x591.webp\" class=\"attachment-large size-large wp-image-29189\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1-1024x591.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1-300x173.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1-768x443.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1-1536x886.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-1.webp 1950w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6692f20 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6692f20\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41aa995\" data-id=\"41aa995\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c3a1f7 elementor-widget elementor-widget-heading\" data-id=\"9c3a1f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">Option 2 Base perm\u00e9able<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ede0ca6 elementor-widget elementor-widget-text-editor\" data-id=\"ede0ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une g\u00e9otextile\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-geogrille-geotextile\/gator-fabric-gf4-4\/\">Gator Fabric GF4.4<\/a>\u00a0couvrant le fond et les c\u00f4t\u00e9s de la zone excav\u00e9e.<\/li><li>4-6\u201d (10-15 cm) de pierre concass\u00e9e et compact\u00e9e de 1-1\/2\u201d (38 mm).<\/li><li>2\u201d (50 mm) de pierre de \u00be\u201d (20 mm) bien compact\u00e9e.<\/li><li>Lit de pose de 1-2\u201d (25-50 mm) de pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloqueront*) (<a href=\"https:\/\/www.youtube.com\/embed\/MkH1_MIB750\" target=\"_blank\" rel=\"noopener\">ASTM N\u00b0 9<\/a>).<\/li><li>\u00c9taler et lisser la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0sur la couche de pierre de 3\/4\u201d (20 mm) et s\u2019assurer que la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0\u00e9pouse le cot\u00e9 et le dessous des pav\u00e9s sur 1\u2019\u2019 (25 mm). Voir le diagramme 2.<\/li><\/ul><div class=\"elementor-element elementor-element-4a6cfc8 elementor-widget elementor-widget-text-editor\" data-id=\"4a6cfc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\">\u00a0<\/div><\/div><div class=\"elementor-element elementor-element-f51f03e elementor-widget elementor-widget-text-editor\" data-id=\"f51f03e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p><span class=\"bold-text-alliance\">N.B. Le GATOR NITRO-X<\/span>\u00a0pourra \u00eatre install\u00e9 seulement 90 minutes apr\u00e8s que la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0a \u00e9t\u00e9 appliqu\u00e9e<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a81881b\" data-id=\"a81881b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a8db6b elementor-widget elementor-widget-image\" data-id=\"1a8db6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gator-nitro-x-jan-13-2025cdn-fr-diagram-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxODgsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvZ2F0b3Itbml0cm8teC1qYW4tMTMtMjAyNWNkbi1mci1kaWFncmFtLTIud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"462\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2-1024x591.webp\" class=\"attachment-large size-large wp-image-29188\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2-1024x591.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2-300x173.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2-768x443.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2-1536x886.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-2.webp 1950w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52cb4d0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52cb4d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d1d5feb\" data-id=\"d1d5feb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e21f11 elementor-widget elementor-widget-heading\" data-id=\"0e21f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">Option 3 Base hybride<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-424a7d3 elementor-widget elementor-widget-text-editor\" data-id=\"424a7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f51f03e elementor-widget elementor-widget-text-editor\" data-id=\"f51f03e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-element elementor-element-20a623a elementor-widget elementor-widget-text-editor\" data-id=\"20a623a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><ul><li>Une g\u00e9otextile\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-geogrille-geotextile\/gator-fabric-gf4-4\/\">Gator Fabric GF4.4<\/a>\u00a0couvrant le fond et les c\u00f4t\u00e9s de la zone excav\u00e9e.<\/li><li>Fondation en pierre 3\/4\u201d (20 mm) concass\u00e9e et compact\u00e9e, sur 4-6\u2019\u2019 (10-15 cm) d\u2019\u00e9paisseur.<\/li><li>Lit de pose de 1\u201d (25 mm) constitu\u00e9e de pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloqueront*) (<a href=\"https:\/\/www.youtube.com\/embed\/MkH1_MIB750\" target=\"_blank\" rel=\"noopener\">ASTM N\u00b0 9<\/a>).<\/li><li>\u00c9taler et lisser la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0sur la couche de pierre net 3\/4\u201d (20 mm) et s\u2019assurer que la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0\u00e9pouse le cot\u00e9 et le dessous des pav\u00e9s sur 1\u2019\u2019 (25 mm). Voir le diagramme 3.<\/li><\/ul><\/div><\/div><div class=\"elementor-element elementor-element-4b7e7d1 elementor-widget elementor-widget-text-editor\" data-id=\"4b7e7d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p><span class=\"bold-text-alliance\">N.B.<\/span>\u00a0Le\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0pourra \u00eatre install\u00e9 seulement 90 minutes apr\u00e8s que la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-xtreme-edge\/\">Gator XTreme<\/a>\u00a0a \u00e9t\u00e9 appliqu\u00e9e.<\/p><\/div><\/div><div class=\"elementor-element elementor-element-f758573 elementor-widget elementor-widget-text-editor\" data-id=\"f758573\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>* Le bloquage fait r\u00e9f\u00e9rence \u00e0 des pierres de taille (ASTM N\u00b0 9 de 1\/8\u201d \u2013 1\/4\u201d (3 mm \u2013 6 mm)) qui emp\u00eachent le\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X\u00a0<\/span>de migrer \u00e0 travers les vides.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b833ac\" data-id=\"2b833ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3541f5 elementor-widget elementor-widget-image\" data-id=\"c3541f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gator-nitro-x-jan-13-2025cdn-fr-diagram-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxODcsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvZ2F0b3Itbml0cm8teC1qYW4tMTMtMjAyNWNkbi1mci1kaWFncmFtLTMud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"462\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3-1024x591.webp\" class=\"attachment-large size-large wp-image-29187\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3-1024x591.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3-300x173.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3-768x443.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3-1536x886.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-3.webp 1950w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-088c1aa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"088c1aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6845e04\" data-id=\"6845e04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7971f elementor-widget elementor-widget-image\" data-id=\"9e7971f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Logo-GatorBase-1.png\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU1NzEsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8xMFwvTG9nby1HYXRvckJhc2UtMS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"205\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png\" class=\"attachment-large size-large wp-image-25571\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png 640w, https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1-300x96.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9163b9 elementor-widget elementor-widget-heading\" data-id=\"a9163b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">Option 4a Gator Base (usage pi\u00e9tonnier uniquement)<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53fdef2 elementor-widget elementor-widget-text-editor\" data-id=\"53fdef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f51f03e elementor-widget elementor-widget-text-editor\" data-id=\"f51f03e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-element elementor-element-f758573 elementor-widget elementor-widget-text-editor\" data-id=\"f758573\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><ul><li>Une g\u00e9otextile <a href=\"https:\/\/flex-lock.com\/fr\/gator-geogrille-geotextile\/gator-fabric-gf4-4\/\">Gator Fabric GF4.4<\/a>\u00a0couvrant le fond et les c\u00f4t\u00e9s de la zone excav\u00e9e.<\/li><li>Lit de sable compact\u00e9 de 3\/4\u201d -1\u201d (20-25 mm) ou de pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloquent*) (<a href=\"https:\/\/www.youtube.com\/embed\/MkH1_MIB750\" target=\"_blank\" rel=\"noopener\">ASTM N\u00b0 9<\/a>).<\/li><li>L\u2019 installation de la\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-base\/\">Gator Base<\/a>\u00a0d\u00e9passant de 6\u201d (15 cm) la surface finale des pav\u00e9s.<\/li><li>Identique \u00e0 la m\u00e9thode traditionnelle.<\/li><li>Visser la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-edge-flex-rigide\/\">Gator Edge<\/a>\u00a0sur la\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-base\/\">Gator Base<\/a>\u00a0\u00e0 tous les 2 trous et s\u2019assurer que la section verticale de la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/bordures-fixations\/gator-edge-flex-rigide\/\">Gator Edge<\/a>\u00a0\u00e9pouse les pav\u00e9s. Voir le diagramme 4A.<\/li><\/ul><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a07444b\" data-id=\"a07444b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98217cd elementor-widget elementor-widget-image\" data-id=\"98217cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gator-nitro-x-jan-13-2025cdn-fr-diagram-4a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxODYsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvZ2F0b3Itbml0cm8teC1qYW4tMTMtMjAyNWNkbi1mci1kaWFncmFtLTRhLndlYnAifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"462\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a-1024x591.webp\" class=\"attachment-large size-large wp-image-29186\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a-1024x591.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a-300x173.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a-768x443.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a-1536x886.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4a.webp 1950w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e1da606 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1da606\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-81eeed2\" data-id=\"81eeed2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2471f28 elementor-widget elementor-widget-image\" data-id=\"2471f28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Logo-GatorBase-1.png\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU1NzEsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8xMFwvTG9nby1HYXRvckJhc2UtMS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"205\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png\" class=\"attachment-large size-large wp-image-25571\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1.png 640w, https:\/\/flex-lock.com\/wp-content\/uploads\/2022\/10\/Logo-GatorBase-1-300x96.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67bf298 elementor-widget elementor-widget-heading\" data-id=\"67bf298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"bold-text-alliance\">Option 4b Gator Base (usage pi\u00e9tonnier uniquement) avec le syst\u00e8me Gator Tile<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0226a9e elementor-widget elementor-widget-text-editor\" data-id=\"0226a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f51f03e elementor-widget elementor-widget-text-editor\" data-id=\"f51f03e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-element elementor-element-f758573 elementor-widget elementor-widget-text-editor\" data-id=\"f758573\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><ul><li>Une g\u00e9otextile\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-geogrille-geotextile\/gator-fabric-gf4-4\/\">Gator Fabric GF4.4<\/a>\u00a0couvrant le fond et les c\u00f4t\u00e9s de la zone excav\u00e9e.<\/li><li>Lit de sable compact\u00e9 de 3\/4\u201d -1\u201d (20-25 mm) ou de pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloquent*) (<a href=\"https:\/\/www.youtube.com\/embed\/MkH1_MIB750\" target=\"_blank\" rel=\"noopener\">ASTM N\u00b0 9<\/a>).<\/li><li>L\u2019 installation de la\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-base\/\">Gator Base<\/a>\u00a0d\u00e9passant de 6\u201d (15 cm) la surface finale de tuiles de porcelaine.<\/li><li>Installer les tuiles de porcelaine \u00e0 l\u2019aide des plots\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/systeme-gator-tile\/\">Gator Spacer<\/a>\u00a0(1\/8\u201d, 3\/16\u201d ou 1\/4\u201d (3 mm, 5 mm ou 6 mm)) et de la colle\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/agents-liants-gator\/block-bond-xp\/\">Gator XP<\/a>\u00a0pour assurer une liaison m\u00e9canique et l\u2019int\u00e9grit\u00e9 structurelle du syst\u00e8me.<\/li><li>Installer la bordure\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/systeme-gator-tile\/\">Gator Tile<\/a>\u00a0contre les tuiles de porcelaine et utiliser des vis Gator Base tous les deux trous sur la\u00a0<a href=\"https:\/\/flex-lock.com\/fr\/gator-base\/\">Gator Base<\/a>.<\/li><\/ul><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db6133b\" data-id=\"db6133b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9862ac elementor-widget elementor-widget-image\" data-id=\"d9862ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gator-nitro-x-jan-13-2025cdn-fr-diagram-4b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxODUsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvZ2F0b3Itbml0cm8teC1qYW4tMTMtMjAyNWNkbi1mci1kaWFncmFtLTRiLndlYnAifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"462\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b-1024x591.webp\" class=\"attachment-large size-large wp-image-29185\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b-1024x591.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b-300x173.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b-768x443.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b-1536x886.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/gator-nitro-x-jan-13-2025cdn-fr-diagram-4b.webp 1950w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5829fef9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5829fef9\" data-element_type=\"section\" data-e-type=\"section\" id=\"installation\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fb226f\" data-id=\"6fb226f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48fe50ee elementor-widget elementor-widget-heading\" data-id=\"48fe50ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9TAPES D\u2019INSTALLATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7fc00 elementor-widget elementor-widget-text-editor\" data-id=\"dd7fc00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con\u00e7u pour les applications pi\u00e9tonni\u00e8res et v\u00e9hiculaires,\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0est pr\u00eat \u00e0 l\u2019emploi et ne n\u00e9cessite aucun m\u00e9lange. Apr\u00e8s avoir suivi la PR\u00c9PARATION DE LA SOUS-FONDATION REQUISE d\u00e9crite ci-dessus, l\u2019application du\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0peut commencer. L\u2019installation sera plus facile \u00e0 deux personnes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17dce10b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17dce10b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a585050\" data-id=\"4a585050\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d0ac1fe elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d0ac1fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-71a7fb8a\" data-id=\"71a7fb8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-791780e3 elementor-widget elementor-widget-heading\" data-id=\"791780e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">NOTE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba419f elementor-widget elementor-widget-text-editor\" data-id=\"cba419f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol type=\"A\"><li>Les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur\u00a0<span class=\"bold-text-alliance\">ne doivent pas pr\u00e9senter de mouvement avant ou apr\u00e8s l\u2019installation<\/span>\u00a0de\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0dans les joints. Si les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur bougent ou basculent, cela r\u00e9sulte d\u2019une pr\u00e9paration inad\u00e9quate de la sous-fondation. Pour plus de clart\u00e9,\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0n\u2019emp\u00eachera pas les forces lat\u00e9rales ou de rotation qui sont g\u00e9n\u00e9r\u00e9es sur les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et sur les installations de tuiles de porcelaine, de pav\u00e9s de porcelaine ou de dalles de porcelaine pour ext\u00e9rieur.\u00a0<span class=\"bold-text-alliance\">Tout mouvement d\u2019un mat\u00e9riau de pavage annule la garantie<\/span>.<\/li><li>Il n\u2019est pas n\u00e9cessaire de prot\u00e9ger les joints trait\u00e9s de la pluie pendant la prise. La pr\u00e9sence de pluie peut toutefois retarder le prise. Pleine r\u00e9sistance : 28 jours, mais la surface est praticable apr\u00e8s 18 heures. Si de fortes pluies se sont produites apr\u00e8s le jointoiement, il peut \u00eatre n\u00e9cessaire de revenir sur place par temps clair pour retoucher les joints.<\/li><li><span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0peut \u00eatre appliqu\u00e9 lorsque les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur sont install\u00e9s directement sur des pierres de taille (1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm)) qui se \u00abbloquent\u00bb* elles-m\u00eames. Cela signifie que\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>-X ne migrera pas \u00e0 travers les vides.<\/li><li>Ne pas appliquer\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X\u00a0<\/span>lorsque les pav\u00e9s en b\u00e9ton, les dalles en b\u00e9ton, les pierres naturelles ou les pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur sont install\u00e9s directement sur des agr\u00e9gats pr\u00e9sentant de grands vides.\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X\u00a0<\/span>migrera \u00e0 travers les agr\u00e9gats avec de grands vides.<\/li><li>En suivant soigneusement les instructions d\u2019installation du\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>, vous obtiendrez un mat\u00e9riau de jointoiement tr\u00e8s dur.<\/li><li>Lors de l\u2019installation de pav\u00e9s en b\u00e9ton, de dalles en b\u00e9ton, de pierres naturelles ou de pierres reconstitu\u00e9es et de tuiles de porcelaine, de pav\u00e9s de porcelaine ou de dalles de porcelaine pour ext\u00e9rieur autour d\u2019une piscine creus\u00e9e, une pente de 1\/8 de pouce (3 mm) par pied lin\u00e9aire (30 cm) \u00e0 l\u2019\u00e9cart de la piscine est obligatoire.<\/li><li>Toutes les surfaces de pav\u00e9s en b\u00e9ton, de dalles en b\u00e9ton, de pierres naturelles ou de pierres reconstitu\u00e9es et de tuiles de porcelaine, de pav\u00e9s de porcelaine ou de dalles de porcelaine pour ext\u00e9rieur doivent avoir une pente de drainage pour que\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0fonctionne de mani\u00e8re optimale.<\/li><li>Pour les blocs de couronnement de piscines, il est obligatoire d\u2019utiliser du mortier dans les joints. Pour le reste des pav\u00e9s en b\u00e9ton, dalles en b\u00e9ton, pierres naturelles ou pierres reconstitu\u00e9es et les tuiles de porcelaine, les pav\u00e9s de porcelaine ou les dalles de porcelaine pour ext\u00e9rieur install\u00e9s autour de la piscine, vous pouvez utiliser\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>.<\/li><\/ol><div class=\"elementor-element elementor-element-fa7c554 elementor-widget elementor-widget-text-editor\" data-id=\"fa7c554\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>\u00a0<\/p><p>* Le bloquage fait r\u00e9f\u00e9rence aux pav\u00e9s en b\u00e9ton, dalles en b\u00e9ton, pierres naturelles ou pierres reconstitu\u00e9es et aux tuiles de porcelaine, pav\u00e9s de porcelaine ou dalles de porcelaine pour ext\u00e9rieur qui sont install\u00e9s directement sur des pierres de taille de 1\/8\u201d \u00e0 1\/4\u201d (3 \u00e0 6 mm) qui se bloquent elles-m\u00eames. Cela signifie que <span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0ne migrera pas \u00e0 travers les vides.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf307c5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf307c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b701cba\" data-id=\"b701cba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac11d1e elementor-widget elementor-widget-heading\" data-id=\"ac11d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9TAPE 1<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13e23c5 elementor-widget elementor-widget-text-editor\" data-id=\"13e23c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mouiller la zone \u00e0 jointoyer. Si la surface est s\u00e8che ou si la temp\u00e9rature est \u00e9lev\u00e9e, il faudra plus d\u2019eau pour ne pas tacher la surface lors de l\u2019\u00e9pandage du\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-90a6bef\" data-id=\"90a6bef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-762a712 elementor-widget elementor-widget-image\" data-id=\"762a712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"20240788-Nitro-NitroX-Installation-Image-Web-Step01-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxOTQsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvMjAyNDA3ODgtTml0cm8tTml0cm9YLUluc3RhbGxhdGlvbi1JbWFnZS1XZWItU3RlcDAxLTEud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-1024x683.webp\" class=\"attachment-large size-large wp-image-29194\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-1024x683.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-300x200.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-768x512.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-1536x1024.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step01-1-2048x1365.webp 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-824c5aa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"824c5aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-82a2ec0\" data-id=\"82a2ec0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-539f60a elementor-widget elementor-widget-heading\" data-id=\"539f60a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9TAPE 2\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de44521 elementor-widget elementor-widget-text-editor\" data-id=\"de44521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ouvrir le sac de\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0et r\u00e9pandre 1\/3 du contenu sur la surface pav\u00e9e. Imbiber compl\u00e8tement le\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0d\u2019eau tout en utilisant une raclette ou un balai \u00e0 poils durs pour \u00e9taler et m\u00e9langer, afin de permettre au GATOR NITRO-X de s\u2019\u00e9couler dans les joints. Continuer \u00e0 appliquer de l\u2019eau tout en utilisant une raclette ou un balai pour pousser\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0en diagonale sur la surface pav\u00e9e et dans les joints. Cette action compacte et force\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>\u00a0dans les joints, garantissant ainsi un remplissage optimal des espaces. S\u2019assurer que les joints sont compl\u00e8tement remplis avant de passer \u00e0 la section suivante. Utiliser un balai \u00e0 poils durs pour les surfaces textur\u00e9es et le r\u00e9glage final de la hauteur des joints.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec9c86c\" data-id=\"ec9c86c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c4fb0 elementor-widget elementor-widget-image\" data-id=\"b1c4fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"20240788-Nitro-NitroX-Installation-Image-Web-Step03-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxOTUsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvMjAyNDA3ODgtTml0cm8tTml0cm9YLUluc3RhbGxhdGlvbi1JbWFnZS1XZWItU3RlcDAzLTEud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-1024x683.webp\" class=\"attachment-large size-large wp-image-29195\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-1024x683.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-300x200.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-768x512.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-1536x1024.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step03-1-2048x1365.webp 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-447d4e1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"447d4e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c57fcfc\" data-id=\"c57fcfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6675cdc elementor-widget elementor-widget-heading\" data-id=\"6675cdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9TAPE 3\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f12754a elementor-widget elementor-widget-text-editor\" data-id=\"f12754a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les joints doivent \u00eatre remplis \u00e0 1\/8\u201d (3 mm) sous la surface sup\u00e9rieure ou \u00e0 1\/8\u201d (3 mm) sous le chanfrein du mat\u00e9riau de pavage s\u00e9lectionn\u00e9 avec\u00a0<span class=\"bold-text-alliance\">GATOR NITRO-X<\/span>. Arroser la surface pour rincer l\u2019exc\u00e8s de mat\u00e9riau de la surface pav\u00e9e. R\u00e9p\u00e9ter les \u00e9tapes 2 et 3 jusqu\u2019\u00e0 ce que toute la zone de pavage soit termin\u00e9e.<br \/><br \/>Les joints sont imm\u00e9diatement r\u00e9sistants \u00e0 la pluie, bien que la pluie retarde le processus de prise. La pleine r\u00e9sistance est atteinte apr\u00e8s 28 jours. La surface peut \u00eatre ouverte \u00e0 la circulation apr\u00e8s la prise initiale, soit environ 18 heures par temps sec et \u00e0 une temp\u00e9rature sup\u00e9rieure \u00e0 24 \u00b0C. Si de fortes pluies se sont produites apr\u00e8s le jointoiement, il peut \u00eatre n\u00e9cessaire de revenir sur place par temps clair pour retoucher les joints.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9daacc1\" data-id=\"9daacc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a199a8 elementor-widget elementor-widget-image\" data-id=\"2a199a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"20240788-Nitro-NitroX-Installation-Image-Web-Step02-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxOTYsInVybCI6Imh0dHBzOlwvXC9mbGV4LWxvY2suY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wOFwvMjAyNDA3ODgtTml0cm8tTml0cm9YLUluc3RhbGxhdGlvbi1JbWFnZS1XZWItU3RlcDAyLTEud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-1024x683.webp\" class=\"attachment-large size-large wp-image-29196\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-1024x683.webp 1024w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-300x200.webp 300w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-768x512.webp 768w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-1536x1024.webp 1536w, https:\/\/flex-lock.com\/wp-content\/uploads\/2025\/08\/20240788-Nitro-NitroX-Installation-Image-Web-Step02-1-2048x1365.webp 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2165952d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2165952d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6498ac8\" data-id=\"6498ac8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f7c05b7 elementor-widget elementor-widget-menu-anchor\" data-id=\"1f7c05b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"garantie\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3be682 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3be682\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1e730523\" data-id=\"1e730523\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-63229ee0\" data-id=\"63229ee0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ac6b618 elementor-widget elementor-widget-image\" data-id=\"3ac6b618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"100\" src=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2021\/10\/Garantie-limitee-5-ans.png\" class=\"attachment-large size-large wp-image-13891\" alt=\"\" srcset=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2021\/10\/Garantie-limitee-5-ans.png 320w, https:\/\/flex-lock.com\/wp-content\/uploads\/2021\/10\/Garantie-limitee-5-ans-300x94.png 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-37eaf117\" data-id=\"37eaf117\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5b7839 elementor-widget elementor-widget-spacer\" data-id=\"a5b7839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4fbdcab2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fbdcab2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dea1740\" data-id=\"dea1740\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92b757e elementor-widget elementor-widget-toggle\" data-id=\"92b757e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1531\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1531\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">GARANTIE LIMIT\u00c9E DE 5 ANS<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1531\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1531\"><p>Avant d\u2019appliquer le produit, l\u2019utilisateur\/l\u2019acheteur doit d\u00e9terminer s\u2019il convient \u00e0 l\u2019usage pr\u00e9vu et il assume tous les risques \u00e0 cet \u00e9gard. La garantie limit\u00e9e pr\u00e9voit qu\u2019avant d\u2019utiliser le produit sur une surface plus grande, l\u2019utilisateur\/l\u2019acheteur doit tester le produit sur une petite surface peu visible d\u2019environ 0,4 m\u00b2 (4 pieds carr\u00e9s) afin de s\u2019assurer que les r\u00e9sultats r\u00e9pondent \u00e0 ses attentes. Si aucun test n\u2019est effectu\u00e9, la garantie limit\u00e9e de 5 ans ne s\u2019appliquera qu\u2019\u00e0 0,4 m\u00b2 (4 pieds carr\u00e9s). Alliance Designer Products Inc. ne peut garantir les r\u00e9sultats car elle n\u2019a aucun contr\u00f4le sur la pr\u00e9paration de la surface et l\u2019application du produit. Si ce produit s\u2019av\u00e8re d\u00e9fectueux, \u00e0 condition qu\u2019il ait \u00e9t\u00e9 appliqu\u00e9 conform\u00e9ment \u00e0 la m\u00e9thode d\u2019application et \u00e0 la pr\u00e9paration de surface requises, la seule obligation d\u2019Alliance Designer Products Inc. est de rembourser le prix d\u2019achat. Une preuve d\u2019achat est requise pour toute r\u00e9clamation. Alliance Designer Products Inc. ne peut \u00eatre tenue responsable de tout autre dommage, direct ou indirect. Dans la mesure permise par la loi, Alliance Designer Products Inc. exclut toute garantie implicite de qualit\u00e9, de qualit\u00e9 marchande ou d\u2019ad\u00e9quation \u00e0 un usage particulier<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1532\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1532\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">GARANTIE LIMIT\u00c9E DE 1 AN (USAGE COMMERCIAL)<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1532\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1532\"><p>Veuillez noter que lorsque le produit est utilis\u00e9 \u00e0 d\u2019autres fins (usage mixte, commercial, institutionnel ou autre), les conditions ci-dessus s\u2019appliquent, sauf que la p\u00e9riode applicable est r\u00e9duite \u00e0 1 an \u00e0 compter de l\u2019achat. ALLIANCE DESIGNER PRODUCTS INC. d\u00e9cline toute responsabilit\u00e9 quant \u00e0 l\u2019utilisation de tout produit GATOR NITRO-X pour toute installation non conforme aux sp\u00e9cifications du fabricant.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1533\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1533\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">EXCLUSION DE RESPONSABILIT\u00c9<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1533\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1533\"><p>LES PARTIES CONVIENNENT QUE LE REMBOURSEMENT DU PRIX D\u2019ACHAT TEL QU\u2019IL EST INDIQU\u00c9 EST LA SEULE OBLIGATION DU FABRICANT. DANS TOUS LES CAS, LE FABRICANT NE SERA PAS RESPONSABLE DES AUTRES DOMMAGES OU CO\u00dbTS QUELS QU\u2019ILS SOIENT (Y COMPRIS L\u2019ENL\u00c8VEMENT OU LA R\u00c9INSTALLATION DU SABLE OU DES PAV\u00c9S), QU\u2019ILS SOIENT DIRECTS OU INDIRECTS. DANS LA MESURE PERMISE PAR LA LOI, LE FABRICANT EXCLUT TOUTE GARANTIE IMPLICITE DE QUALIT\u00c9, DE QUALIT\u00c9 MARCHANDE OU D\u2019AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER. ALLIANCE DESIGNER PRODUCTS INC. n\u2019est pas responsable de la pr\u00e9sence de mousses, de moisissures ou d\u2019autres facteurs similaires qui peuvent se produire sur le produit apr\u00e8s son installation. La pr\u00e9sence de mousses, de moisissures et de mildiou est caus\u00e9e par les conditions particuli\u00e8res du site, notamment l\u2019exc\u00e8s d\u2019humidit\u00e9, l\u2019ombre, l\u2019absence de ventilation, un nettoyage ou entretien inad\u00e9quat, ainsi que la pr\u00e9sence de terre ou d\u2019autres d\u00e9bris organiques laiss\u00e9s sur le produit apr\u00e8s l\u2019installation. ALLIANCE DESIGNER PRODUCTS INC. d\u00e9cline toute responsabilit\u00e9 quant \u00e0 l\u2019utilisation de GATOR NITRO-X pour toute installation non conforme aux sp\u00e9cifications du fabricant. Alliance Designer Products n\u2019est pas responsable de toute utilisation non conforme.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sable fin de jointoiementGator Nitro-X Description Id\u00e9al pour Caract\u00e9ristiques Couleurs Entretien Superficie couverte Entreposage Emballage Description LE SABLE DE JOINTOIEMENT FIN GATOR NITRO-X est le mat\u00e9riau de jointoiement \u00e0 faible perm\u00e9abilit\u00e9 et durcissant lorsque expos\u00e9 \u00e0 l\u2019air. C\u2019est un m\u00e9lange pr\u00eat \u00e0 l\u2019emploi de sable fin calibr\u00e9 et d\u2019une nouvelle formule de r\u00e9sine exclusive qui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27481","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sable fin de jointoiement Gator Nitro-X - Flexlock<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sable fin de jointoiement Gator Nitro-X - Flexlock\" \/>\n<meta property=\"og:description\" content=\"Sable fin de jointoiementGator Nitro-X Description Id\u00e9al pour Caract\u00e9ristiques Couleurs Entretien Superficie couverte Entreposage Emballage Description LE SABLE DE JOINTOIEMENT FIN GATOR NITRO-X est le mat\u00e9riau de jointoiement \u00e0 faible perm\u00e9abilit\u00e9 et durcissant lorsque expos\u00e9 \u00e0 l\u2019air. C\u2019est un m\u00e9lange pr\u00eat \u00e0 l\u2019emploi de sable fin calibr\u00e9 et d\u2019une nouvelle formule de r\u00e9sine exclusive qui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/\" \/>\n<meta property=\"og:site_name\" content=\"Flexlock\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T20:46:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/\",\"url\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/\",\"name\":\"Sable fin de jointoiement Gator Nitro-X - Flexlock\",\"isPartOf\":{\"@id\":\"https:\/\/flex-lock.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp\",\"datePublished\":\"2024-10-09T18:49:00+00:00\",\"dateModified\":\"2026-06-19T20:46:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage\",\"url\":\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp\",\"contentUrl\":\"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/flex-lock.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sable fin de jointoiement Gator Nitro-X\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flex-lock.com\/fr\/#website\",\"url\":\"https:\/\/flex-lock.com\/fr\/\",\"name\":\"Flexlock\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flex-lock.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sable fin de jointoiement Gator Nitro-X - Flexlock","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/","og_locale":"fr_CA","og_type":"article","og_title":"Sable fin de jointoiement Gator Nitro-X - Flexlock","og_description":"Sable fin de jointoiementGator Nitro-X Description Id\u00e9al pour Caract\u00e9ristiques Couleurs Entretien Superficie couverte Entreposage Emballage Description LE SABLE DE JOINTOIEMENT FIN GATOR NITRO-X est le mat\u00e9riau de jointoiement \u00e0 faible perm\u00e9abilit\u00e9 et durcissant lorsque expos\u00e9 \u00e0 l\u2019air. C\u2019est un m\u00e9lange pr\u00eat \u00e0 l\u2019emploi de sable fin calibr\u00e9 et d\u2019une nouvelle formule de r\u00e9sine exclusive qui [&hellip;]","og_url":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/","og_site_name":"Flexlock","article_modified_time":"2026-06-19T20:46:59+00:00","og_image":[{"width":640,"height":206,"url":"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/","url":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/","name":"Sable fin de jointoiement Gator Nitro-X - Flexlock","isPartOf":{"@id":"https:\/\/flex-lock.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage"},"image":{"@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage"},"thumbnailUrl":"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp","datePublished":"2024-10-09T18:49:00+00:00","dateModified":"2026-06-19T20:46:59+00:00","breadcrumb":{"@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#primaryimage","url":"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp","contentUrl":"https:\/\/flex-lock.com\/wp-content\/uploads\/2024\/10\/Logo_GatorNitroSand-X-2592-new-OF-12sept24-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/flex-lock.com\/fr\/sable-fin-de-jointoiement-gator-nitro-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flex-lock.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sable fin de jointoiement Gator Nitro-X"}]},{"@type":"WebSite","@id":"https:\/\/flex-lock.com\/fr\/#website","url":"https:\/\/flex-lock.com\/fr\/","name":"Flexlock","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flex-lock.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/pages\/27481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/comments?post=27481"}],"version-history":[{"count":57,"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/pages\/27481\/revisions"}],"predecessor-version":[{"id":29758,"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/pages\/27481\/revisions\/29758"}],"wp:attachment":[{"href":"https:\/\/flex-lock.com\/fr\/wp-json\/wp\/v2\/media?parent=27481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}